{"id":114,"count":0,"description":"","link":"https:\/\/ostrasorlut.com\/en\/categoria-producto\/label-rouge-en\/","name":"Label Rouge","slug":"label-rouge-en","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Label Rouge Archives - Ostras Sorlut<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ostrasorlut.com\/en\/categoria-producto\/label-rouge-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Label Rouge Archives - Ostras Sorlut\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ostrasorlut.com\/en\/categoria-producto\/label-rouge-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Ostras Sorlut\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/categoria-producto\\\/label-rouge-en\\\/\",\"url\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/categoria-producto\\\/label-rouge-en\\\/\",\"name\":\"Label Rouge Archives - Ostras Sorlut\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/categoria-producto\\\/label-rouge-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/categoria-producto\\\/label-rouge-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Label Rouge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/\",\"name\":\"Ostras Sorlut\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/#organization\",\"name\":\"Ostras Sorlut\",\"url\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ostrasorlut.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logoSorlut_Positivo__1_.ai-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/ostrasorlut.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-logoSorlut_Positivo__1_.ai-removebg-preview.png\",\"width\":512,\"height\":512,\"caption\":\"Ostras Sorlut\"},\"image\":{\"@id\":\"https:\\\/\\\/ostrasorlut.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OstrasDanielSorlut\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ostrasdsorlut\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@ostrasdsorlut\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Label Rouge Archives - Ostras Sorlut","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ostrasorlut.com\/en\/categoria-producto\/label-rouge-en\/","og_locale":"en_US","og_type":"article","og_title":"Label Rouge Archives - Ostras Sorlut","og_url":"https:\/\/ostrasorlut.com\/en\/categoria-producto\/label-rouge-en\/","og_site_name":"Ostras Sorlut","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ostrasorlut.com\/en\/categoria-producto\/label-rouge-en\/","url":"https:\/\/ostrasorlut.com\/en\/categoria-producto\/label-rouge-en\/","name":"Label Rouge Archives - Ostras Sorlut","isPartOf":{"@id":"https:\/\/ostrasorlut.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ostrasorlut.com\/en\/categoria-producto\/label-rouge-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ostrasorlut.com\/en\/categoria-producto\/label-rouge-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ostrasorlut.com\/en\/"},{"@type":"ListItem","position":2,"name":"Label Rouge"}]},{"@type":"WebSite","@id":"https:\/\/ostrasorlut.com\/en\/#website","url":"https:\/\/ostrasorlut.com\/en\/","name":"Ostras Sorlut","description":"","publisher":{"@id":"https:\/\/ostrasorlut.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ostrasorlut.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ostrasorlut.com\/en\/#organization","name":"Ostras Sorlut","url":"https:\/\/ostrasorlut.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ostrasorlut.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ostrasorlut.com\/wp-content\/uploads\/2023\/06\/cropped-logoSorlut_Positivo__1_.ai-removebg-preview.png","contentUrl":"https:\/\/ostrasorlut.com\/wp-content\/uploads\/2023\/06\/cropped-logoSorlut_Positivo__1_.ai-removebg-preview.png","width":512,"height":512,"caption":"Ostras Sorlut"},"image":{"@id":"https:\/\/ostrasorlut.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OstrasDanielSorlut\/","https:\/\/www.instagram.com\/ostrasdsorlut\/","https:\/\/www.tiktok.com\/@ostrasdsorlut"]}]}},"_links":{"self":[{"href":"https:\/\/ostrasorlut.com\/en\/wp-json\/wp\/v2\/product_cat\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ostrasorlut.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ostrasorlut.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/ostrasorlut.com\/en\/wp-json\/wp\/v2\/product?product_cat=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}